{"id":29435,"date":"2018-03-07T11:07:00","date_gmt":"2018-03-07T10:07:00","guid":{"rendered":"https:\/\/bordeaux.intercontinental.com\/?p=29435"},"modified":"2024-02-09T15:55:20","modified_gmt":"2024-02-09T14:55:20","slug":"masterclass-vinos-y-chocolates","status":"publish","type":"post","link":"https:\/\/bordeaux.intercontinental.com\/es\/masterclass-vinos-y-chocolates\/","title":{"rendered":"MasterClass Vinos y Chocolates"},"content":{"rendered":"\n<p>El InterContinental Bordeaux &#8211; Le Grand Hotel le invita a su MasterClass de Vinos y Chocolates los d\u00edas 24 de marzo y 7 de abril de 17:30 a 18:30. Durante una hora, d\u00e9jese llevar por la sorpresa y la exploraci\u00f3n, entre dos poderes gastron\u00f3micos de fuerte car\u00e1cter. Para un deleite puro, nuestro jefe sumiller de Le Pressoir d&#8217;Argent Gordon Ramsay le har\u00e1 descubrir la combinaci\u00f3n perfecta de cinco chocolates de la casa Valrhona y vinos de nuestra bodega. Tambi\u00e9n tendr\u00e1 el placer de llevarse a casa el Huevo de Pascua Yves Klein por Arthur F\u00e8vre, nuestro chef pastelero ejecutivo. 45 euros por persona (Huevo de Pascua Yves Klein por Arthur F\u00e8vre incluido). Reserve su lugar antes del 22 de marzo al 05 57 30 43 31 o marketing.bordeaux@ihg.com. Tambi\u00e9n disponible como regalo en nuestra p\u00e1gina web www.bordeaux.intercontinental.com.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El InterContinental Bordeaux &#8211; Le Grand Hotel le invita a su MasterClass de Vinos y Chocolates los d\u00edas 24 de marzo y 7 de abril de 17:30 a 18:30. Durante una hora, d\u00e9jese llevar por la sorpresa y la exploraci\u00f3n, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":23564,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[92],"tags":[],"class_list":["post-29435","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categorizar"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>MasterClass Vinos y Chocolates - InterContinental Bordeaux<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/bordeaux.intercontinental.com\/es\/masterclass-vinos-y-chocolates\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"MasterClass Vinos y Chocolates - InterContinental Bordeaux\" \/>\n<meta property=\"og:description\" content=\"El InterContinental Bordeaux &#8211; Le Grand Hotel le invita a su MasterClass de Vinos y Chocolates los d\u00edas 24 de marzo y 7 de abril de 17:30 a 18:30. Durante una hora, d\u00e9jese llevar por la sorpresa y la exploraci\u00f3n, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/bordeaux.intercontinental.com\/es\/masterclass-vinos-y-chocolates\/\" \/>\n<meta property=\"og:site_name\" content=\"InterContinental Bordeaux\" \/>\n<meta property=\"article:published_time\" content=\"2018-03-07T10:07:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-02-09T14:55:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/bordeaux.intercontinental.com\/wp-content\/uploads\/sites\/4\/2022\/07\/InterContinental-Bordeaux-Le-Grand-Hotel-Masterclass.png\" \/>\n\t<meta property=\"og:image:width\" content=\"498\" \/>\n\t<meta property=\"og:image:height\" content=\"370\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"netsive\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"netsive\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/bordeaux.intercontinental.com\/es\/masterclass-vinos-y-chocolates\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/bordeaux.intercontinental.com\/es\/masterclass-vinos-y-chocolates\/\"},\"author\":{\"name\":\"netsive\",\"@id\":\"https:\/\/bordeaux.intercontinental.com\/es\/#\/schema\/person\/16ed2393516772cec016ebdc7d6051e6\"},\"headline\":\"MasterClass Vinos y Chocolates\",\"datePublished\":\"2018-03-07T10:07:00+00:00\",\"dateModified\":\"2024-02-09T14:55:20+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/bordeaux.intercontinental.com\/es\/masterclass-vinos-y-chocolates\/\"},\"wordCount\":148,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/bordeaux.intercontinental.com\/es\/#organization\"},\"image\":{\"@id\":\"https:\/\/bordeaux.intercontinental.com\/es\/masterclass-vinos-y-chocolates\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/bordeaux.intercontinental.com\/wp-content\/uploads\/sites\/4\/2022\/07\/InterContinental-Bordeaux-Le-Grand-Hotel-Masterclass.png\",\"articleSection\":[\"Sin categorizar\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/bordeaux.intercontinental.com\/es\/masterclass-vinos-y-chocolates\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/bordeaux.intercontinental.com\/es\/masterclass-vinos-y-chocolates\/\",\"url\":\"https:\/\/bordeaux.intercontinental.com\/es\/masterclass-vinos-y-chocolates\/\",\"name\":\"MasterClass Vinos y Chocolates - InterContinental Bordeaux\",\"isPartOf\":{\"@id\":\"https:\/\/bordeaux.intercontinental.com\/es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/bordeaux.intercontinental.com\/es\/masterclass-vinos-y-chocolates\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/bordeaux.intercontinental.com\/es\/masterclass-vinos-y-chocolates\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/bordeaux.intercontinental.com\/wp-content\/uploads\/sites\/4\/2022\/07\/InterContinental-Bordeaux-Le-Grand-Hotel-Masterclass.png\",\"datePublished\":\"2018-03-07T10:07:00+00:00\",\"dateModified\":\"2024-02-09T14:55:20+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/bordeaux.intercontinental.com\/es\/masterclass-vinos-y-chocolates\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/bordeaux.intercontinental.com\/es\/masterclass-vinos-y-chocolates\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/bordeaux.intercontinental.com\/es\/masterclass-vinos-y-chocolates\/#primaryimage\",\"url\":\"https:\/\/bordeaux.intercontinental.com\/wp-content\/uploads\/sites\/4\/2022\/07\/InterContinental-Bordeaux-Le-Grand-Hotel-Masterclass.png\",\"contentUrl\":\"https:\/\/bordeaux.intercontinental.com\/wp-content\/uploads\/sites\/4\/2022\/07\/InterContinental-Bordeaux-Le-Grand-Hotel-Masterclass.png\",\"width\":498,\"height\":370},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/bordeaux.intercontinental.com\/es\/masterclass-vinos-y-chocolates\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\/\/bordeaux.intercontinental.com\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"MasterClass Vinos y Chocolates\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/bordeaux.intercontinental.com\/es\/#website\",\"url\":\"https:\/\/bordeaux.intercontinental.com\/es\/\",\"name\":\"InterContinental Bordeaux\",\"description\":\"Live the InterContinental Life\",\"publisher\":{\"@id\":\"https:\/\/bordeaux.intercontinental.com\/es\/#organization\"},\"alternateName\":\"InterContinental Bordeaux - Le Grand H\u00f4tel\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/bordeaux.intercontinental.com\/es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/bordeaux.intercontinental.com\/es\/#organization\",\"name\":\"InterContinental Bordeaux\",\"alternateName\":\"InterContinental Bordeaux - Le Grand H\u00f4tel\",\"url\":\"https:\/\/bordeaux.intercontinental.com\/es\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/bordeaux.intercontinental.com\/es\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/bordeaux.intercontinental.com\/wp-content\/uploads\/sites\/4\/2023\/08\/logo-ihg-bordeaux-nl.svg\",\"contentUrl\":\"https:\/\/bordeaux.intercontinental.com\/wp-content\/uploads\/sites\/4\/2023\/08\/logo-ihg-bordeaux-nl.svg\",\"caption\":\"InterContinental Bordeaux\"},\"image\":{\"@id\":\"https:\/\/bordeaux.intercontinental.com\/es\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/bordeaux.intercontinental.com\/es\/#\/schema\/person\/16ed2393516772cec016ebdc7d6051e6\",\"name\":\"netsive\",\"sameAs\":[\"http:\/\/intercontinental.development.netsive.com\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"MasterClass Vinos y Chocolates - InterContinental Bordeaux","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/bordeaux.intercontinental.com\/es\/masterclass-vinos-y-chocolates\/","og_locale":"es_ES","og_type":"article","og_title":"MasterClass Vinos y Chocolates - InterContinental Bordeaux","og_description":"El InterContinental Bordeaux &#8211; Le Grand Hotel le invita a su MasterClass de Vinos y Chocolates los d\u00edas 24 de marzo y 7 de abril de 17:30 a 18:30. Durante una hora, d\u00e9jese llevar por la sorpresa y la exploraci\u00f3n, [&hellip;]","og_url":"https:\/\/bordeaux.intercontinental.com\/es\/masterclass-vinos-y-chocolates\/","og_site_name":"InterContinental Bordeaux","article_published_time":"2018-03-07T10:07:00+00:00","article_modified_time":"2024-02-09T14:55:20+00:00","og_image":[{"width":498,"height":370,"url":"https:\/\/bordeaux.intercontinental.com\/wp-content\/uploads\/sites\/4\/2022\/07\/InterContinental-Bordeaux-Le-Grand-Hotel-Masterclass.png","type":"image\/png"}],"author":"netsive","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"netsive","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/bordeaux.intercontinental.com\/es\/masterclass-vinos-y-chocolates\/#article","isPartOf":{"@id":"https:\/\/bordeaux.intercontinental.com\/es\/masterclass-vinos-y-chocolates\/"},"author":{"name":"netsive","@id":"https:\/\/bordeaux.intercontinental.com\/es\/#\/schema\/person\/16ed2393516772cec016ebdc7d6051e6"},"headline":"MasterClass Vinos y Chocolates","datePublished":"2018-03-07T10:07:00+00:00","dateModified":"2024-02-09T14:55:20+00:00","mainEntityOfPage":{"@id":"https:\/\/bordeaux.intercontinental.com\/es\/masterclass-vinos-y-chocolates\/"},"wordCount":148,"commentCount":0,"publisher":{"@id":"https:\/\/bordeaux.intercontinental.com\/es\/#organization"},"image":{"@id":"https:\/\/bordeaux.intercontinental.com\/es\/masterclass-vinos-y-chocolates\/#primaryimage"},"thumbnailUrl":"https:\/\/bordeaux.intercontinental.com\/wp-content\/uploads\/sites\/4\/2022\/07\/InterContinental-Bordeaux-Le-Grand-Hotel-Masterclass.png","articleSection":["Sin categorizar"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/bordeaux.intercontinental.com\/es\/masterclass-vinos-y-chocolates\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/bordeaux.intercontinental.com\/es\/masterclass-vinos-y-chocolates\/","url":"https:\/\/bordeaux.intercontinental.com\/es\/masterclass-vinos-y-chocolates\/","name":"MasterClass Vinos y Chocolates - InterContinental Bordeaux","isPartOf":{"@id":"https:\/\/bordeaux.intercontinental.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/bordeaux.intercontinental.com\/es\/masterclass-vinos-y-chocolates\/#primaryimage"},"image":{"@id":"https:\/\/bordeaux.intercontinental.com\/es\/masterclass-vinos-y-chocolates\/#primaryimage"},"thumbnailUrl":"https:\/\/bordeaux.intercontinental.com\/wp-content\/uploads\/sites\/4\/2022\/07\/InterContinental-Bordeaux-Le-Grand-Hotel-Masterclass.png","datePublished":"2018-03-07T10:07:00+00:00","dateModified":"2024-02-09T14:55:20+00:00","breadcrumb":{"@id":"https:\/\/bordeaux.intercontinental.com\/es\/masterclass-vinos-y-chocolates\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/bordeaux.intercontinental.com\/es\/masterclass-vinos-y-chocolates\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/bordeaux.intercontinental.com\/es\/masterclass-vinos-y-chocolates\/#primaryimage","url":"https:\/\/bordeaux.intercontinental.com\/wp-content\/uploads\/sites\/4\/2022\/07\/InterContinental-Bordeaux-Le-Grand-Hotel-Masterclass.png","contentUrl":"https:\/\/bordeaux.intercontinental.com\/wp-content\/uploads\/sites\/4\/2022\/07\/InterContinental-Bordeaux-Le-Grand-Hotel-Masterclass.png","width":498,"height":370},{"@type":"BreadcrumbList","@id":"https:\/\/bordeaux.intercontinental.com\/es\/masterclass-vinos-y-chocolates\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/bordeaux.intercontinental.com\/es\/"},{"@type":"ListItem","position":2,"name":"MasterClass Vinos y Chocolates"}]},{"@type":"WebSite","@id":"https:\/\/bordeaux.intercontinental.com\/es\/#website","url":"https:\/\/bordeaux.intercontinental.com\/es\/","name":"InterContinental Bordeaux","description":"Live the InterContinental Life","publisher":{"@id":"https:\/\/bordeaux.intercontinental.com\/es\/#organization"},"alternateName":"InterContinental Bordeaux - Le Grand H\u00f4tel","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/bordeaux.intercontinental.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/bordeaux.intercontinental.com\/es\/#organization","name":"InterContinental Bordeaux","alternateName":"InterContinental Bordeaux - Le Grand H\u00f4tel","url":"https:\/\/bordeaux.intercontinental.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/bordeaux.intercontinental.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/bordeaux.intercontinental.com\/wp-content\/uploads\/sites\/4\/2023\/08\/logo-ihg-bordeaux-nl.svg","contentUrl":"https:\/\/bordeaux.intercontinental.com\/wp-content\/uploads\/sites\/4\/2023\/08\/logo-ihg-bordeaux-nl.svg","caption":"InterContinental Bordeaux"},"image":{"@id":"https:\/\/bordeaux.intercontinental.com\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/bordeaux.intercontinental.com\/es\/#\/schema\/person\/16ed2393516772cec016ebdc7d6051e6","name":"netsive","sameAs":["http:\/\/intercontinental.development.netsive.com"]}]}},"_links":{"self":[{"href":"https:\/\/bordeaux.intercontinental.com\/es\/wp-json\/wp\/v2\/posts\/29435","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bordeaux.intercontinental.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bordeaux.intercontinental.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bordeaux.intercontinental.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/bordeaux.intercontinental.com\/es\/wp-json\/wp\/v2\/comments?post=29435"}],"version-history":[{"count":0,"href":"https:\/\/bordeaux.intercontinental.com\/es\/wp-json\/wp\/v2\/posts\/29435\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bordeaux.intercontinental.com\/es\/wp-json\/wp\/v2\/media\/23564"}],"wp:attachment":[{"href":"https:\/\/bordeaux.intercontinental.com\/es\/wp-json\/wp\/v2\/media?parent=29435"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bordeaux.intercontinental.com\/es\/wp-json\/wp\/v2\/categories?post=29435"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bordeaux.intercontinental.com\/es\/wp-json\/wp\/v2\/tags?post=29435"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}