{"id":29431,"date":"2018-02-05T11:03:00","date_gmt":"2018-02-05T10:03:00","guid":{"rendered":"https:\/\/bordeaux.intercontinental.com\/?p=29431"},"modified":"2024-02-09T15:51:53","modified_gmt":"2024-02-09T14:51:53","slug":"le-pressoir-dargent-2-estrellas-en-la-guia-michelin-2018","status":"publish","type":"post","link":"https:\/\/bordeaux.intercontinental.com\/es\/le-pressoir-dargent-2-estrellas-en-la-guia-michelin-2018\/","title":{"rendered":"Le Pressoir d&#8217;Argent : 2 estrellas en la Gu\u00eda Michelin 2018"},"content":{"rendered":"\n<p>2 ESTRELLAS EN LA GU\u00cdA MICHELIN\u00a0: LE PRESSOIR D\u2019ARGENT \u2013 COCINA MODERNA \u2013 ELEGANTE Despu\u00e9s de haber ganado una primera estrella Michelin en 2016, seguida de una segunda en 2017, estamos orgullosos de anunciar que hemos conservado nuestras dos estrellas Michelin en este a\u00f1o 2018.<\/p>\n\n\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/bordeaux.intercontinental.com\/wp-content\/uploads\/sites\/4\/2022\/09\/InterContinental-Bordeaux-Le-Grand-Hotel-Michelin-2-Stars.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">Saber m\u00e1s<\/a><\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>2 ESTRELLAS EN LA GU\u00cdA MICHELIN\u00a0: LE PRESSOIR D\u2019ARGENT \u2013 COCINA MODERNA \u2013 ELEGANTE Despu\u00e9s de haber ganado una primera estrella Michelin en 2016, seguida de una segunda en 2017, estamos orgullosos de anunciar que hemos conservado nuestras dos estrellas [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":23522,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[127],"tags":[],"class_list":["post-29431","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Le Pressoir d&#039;Argent : 2 estrellas en la Gu\u00eda Michelin 2018 - InterContinental Bordeaux<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/bordeaux.intercontinental.com\/es\/le-pressoir-dargent-2-estrellas-en-la-guia-michelin-2018\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Le Pressoir d&#039;Argent : 2 estrellas en la Gu\u00eda Michelin 2018 - InterContinental Bordeaux\" \/>\n<meta property=\"og:description\" content=\"2 ESTRELLAS EN LA GU\u00cdA MICHELIN\u00a0: LE PRESSOIR D\u2019ARGENT \u2013 COCINA MODERNA \u2013 ELEGANTE Despu\u00e9s de haber ganado una primera estrella Michelin en 2016, seguida de una segunda en 2017, estamos orgullosos de anunciar que hemos conservado nuestras dos estrellas [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/bordeaux.intercontinental.com\/es\/le-pressoir-dargent-2-estrellas-en-la-guia-michelin-2018\/\" \/>\n<meta property=\"og:site_name\" content=\"InterContinental Bordeaux\" \/>\n<meta property=\"article:published_time\" content=\"2018-02-05T10:03:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-02-09T14:51:53+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/bordeaux.intercontinental.com\/wp-content\/uploads\/sites\/4\/2022\/07\/InterContinental-Bordeaux-Le-Grand-Hotel-Le-pressoir-Bordeaux-le-grand-hotel-intercontinental-7-scaled-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1707\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"netsive\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"netsive\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/bordeaux.intercontinental.com\/es\/le-pressoir-dargent-2-estrellas-en-la-guia-michelin-2018\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/bordeaux.intercontinental.com\/es\/le-pressoir-dargent-2-estrellas-en-la-guia-michelin-2018\/\"},\"author\":{\"name\":\"netsive\",\"@id\":\"https:\/\/bordeaux.intercontinental.com\/es\/#\/schema\/person\/16ed2393516772cec016ebdc7d6051e6\"},\"headline\":\"Le Pressoir d&#8217;Argent : 2 estrellas en la Gu\u00eda Michelin 2018\",\"datePublished\":\"2018-02-05T10:03:00+00:00\",\"dateModified\":\"2024-02-09T14:51:53+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/bordeaux.intercontinental.com\/es\/le-pressoir-dargent-2-estrellas-en-la-guia-michelin-2018\/\"},\"wordCount\":56,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/bordeaux.intercontinental.com\/es\/#organization\"},\"image\":{\"@id\":\"https:\/\/bordeaux.intercontinental.com\/es\/le-pressoir-dargent-2-estrellas-en-la-guia-michelin-2018\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/bordeaux.intercontinental.com\/wp-content\/uploads\/sites\/4\/2022\/07\/InterContinental-Bordeaux-Le-Grand-Hotel-Le-pressoir-Bordeaux-le-grand-hotel-intercontinental-7-scaled-1.jpg\",\"articleSection\":[\"Noticias\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/bordeaux.intercontinental.com\/es\/le-pressoir-dargent-2-estrellas-en-la-guia-michelin-2018\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/bordeaux.intercontinental.com\/es\/le-pressoir-dargent-2-estrellas-en-la-guia-michelin-2018\/\",\"url\":\"https:\/\/bordeaux.intercontinental.com\/es\/le-pressoir-dargent-2-estrellas-en-la-guia-michelin-2018\/\",\"name\":\"Le Pressoir d'Argent : 2 estrellas en la Gu\u00eda Michelin 2018 - InterContinental Bordeaux\",\"isPartOf\":{\"@id\":\"https:\/\/bordeaux.intercontinental.com\/es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/bordeaux.intercontinental.com\/es\/le-pressoir-dargent-2-estrellas-en-la-guia-michelin-2018\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/bordeaux.intercontinental.com\/es\/le-pressoir-dargent-2-estrellas-en-la-guia-michelin-2018\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/bordeaux.intercontinental.com\/wp-content\/uploads\/sites\/4\/2022\/07\/InterContinental-Bordeaux-Le-Grand-Hotel-Le-pressoir-Bordeaux-le-grand-hotel-intercontinental-7-scaled-1.jpg\",\"datePublished\":\"2018-02-05T10:03:00+00:00\",\"dateModified\":\"2024-02-09T14:51:53+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/bordeaux.intercontinental.com\/es\/le-pressoir-dargent-2-estrellas-en-la-guia-michelin-2018\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/bordeaux.intercontinental.com\/es\/le-pressoir-dargent-2-estrellas-en-la-guia-michelin-2018\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/bordeaux.intercontinental.com\/es\/le-pressoir-dargent-2-estrellas-en-la-guia-michelin-2018\/#primaryimage\",\"url\":\"https:\/\/bordeaux.intercontinental.com\/wp-content\/uploads\/sites\/4\/2022\/07\/InterContinental-Bordeaux-Le-Grand-Hotel-Le-pressoir-Bordeaux-le-grand-hotel-intercontinental-7-scaled-1.jpg\",\"contentUrl\":\"https:\/\/bordeaux.intercontinental.com\/wp-content\/uploads\/sites\/4\/2022\/07\/InterContinental-Bordeaux-Le-Grand-Hotel-Le-pressoir-Bordeaux-le-grand-hotel-intercontinental-7-scaled-1.jpg\",\"width\":2560,\"height\":1707},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/bordeaux.intercontinental.com\/es\/le-pressoir-dargent-2-estrellas-en-la-guia-michelin-2018\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\/\/bordeaux.intercontinental.com\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Le Pressoir d&rsquo;Argent : 2 estrellas en la Gu\u00eda Michelin 2018\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/bordeaux.intercontinental.com\/es\/#website\",\"url\":\"https:\/\/bordeaux.intercontinental.com\/es\/\",\"name\":\"InterContinental Bordeaux\",\"description\":\"Live the InterContinental Life\",\"publisher\":{\"@id\":\"https:\/\/bordeaux.intercontinental.com\/es\/#organization\"},\"alternateName\":\"InterContinental Bordeaux - Le Grand H\u00f4tel\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/bordeaux.intercontinental.com\/es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/bordeaux.intercontinental.com\/es\/#organization\",\"name\":\"InterContinental Bordeaux\",\"alternateName\":\"InterContinental Bordeaux - Le Grand H\u00f4tel\",\"url\":\"https:\/\/bordeaux.intercontinental.com\/es\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/bordeaux.intercontinental.com\/es\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/bordeaux.intercontinental.com\/wp-content\/uploads\/sites\/4\/2023\/08\/logo-ihg-bordeaux-nl.svg\",\"contentUrl\":\"https:\/\/bordeaux.intercontinental.com\/wp-content\/uploads\/sites\/4\/2023\/08\/logo-ihg-bordeaux-nl.svg\",\"caption\":\"InterContinental Bordeaux\"},\"image\":{\"@id\":\"https:\/\/bordeaux.intercontinental.com\/es\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/bordeaux.intercontinental.com\/es\/#\/schema\/person\/16ed2393516772cec016ebdc7d6051e6\",\"name\":\"netsive\",\"sameAs\":[\"http:\/\/intercontinental.development.netsive.com\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Le Pressoir d'Argent : 2 estrellas en la Gu\u00eda Michelin 2018 - InterContinental Bordeaux","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/bordeaux.intercontinental.com\/es\/le-pressoir-dargent-2-estrellas-en-la-guia-michelin-2018\/","og_locale":"es_ES","og_type":"article","og_title":"Le Pressoir d'Argent : 2 estrellas en la Gu\u00eda Michelin 2018 - InterContinental Bordeaux","og_description":"2 ESTRELLAS EN LA GU\u00cdA MICHELIN\u00a0: LE PRESSOIR D\u2019ARGENT \u2013 COCINA MODERNA \u2013 ELEGANTE Despu\u00e9s de haber ganado una primera estrella Michelin en 2016, seguida de una segunda en 2017, estamos orgullosos de anunciar que hemos conservado nuestras dos estrellas [&hellip;]","og_url":"https:\/\/bordeaux.intercontinental.com\/es\/le-pressoir-dargent-2-estrellas-en-la-guia-michelin-2018\/","og_site_name":"InterContinental Bordeaux","article_published_time":"2018-02-05T10:03:00+00:00","article_modified_time":"2024-02-09T14:51:53+00:00","og_image":[{"width":2560,"height":1707,"url":"https:\/\/bordeaux.intercontinental.com\/wp-content\/uploads\/sites\/4\/2022\/07\/InterContinental-Bordeaux-Le-Grand-Hotel-Le-pressoir-Bordeaux-le-grand-hotel-intercontinental-7-scaled-1.jpg","type":"image\/jpeg"}],"author":"netsive","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"netsive","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/bordeaux.intercontinental.com\/es\/le-pressoir-dargent-2-estrellas-en-la-guia-michelin-2018\/#article","isPartOf":{"@id":"https:\/\/bordeaux.intercontinental.com\/es\/le-pressoir-dargent-2-estrellas-en-la-guia-michelin-2018\/"},"author":{"name":"netsive","@id":"https:\/\/bordeaux.intercontinental.com\/es\/#\/schema\/person\/16ed2393516772cec016ebdc7d6051e6"},"headline":"Le Pressoir d&#8217;Argent : 2 estrellas en la Gu\u00eda Michelin 2018","datePublished":"2018-02-05T10:03:00+00:00","dateModified":"2024-02-09T14:51:53+00:00","mainEntityOfPage":{"@id":"https:\/\/bordeaux.intercontinental.com\/es\/le-pressoir-dargent-2-estrellas-en-la-guia-michelin-2018\/"},"wordCount":56,"commentCount":0,"publisher":{"@id":"https:\/\/bordeaux.intercontinental.com\/es\/#organization"},"image":{"@id":"https:\/\/bordeaux.intercontinental.com\/es\/le-pressoir-dargent-2-estrellas-en-la-guia-michelin-2018\/#primaryimage"},"thumbnailUrl":"https:\/\/bordeaux.intercontinental.com\/wp-content\/uploads\/sites\/4\/2022\/07\/InterContinental-Bordeaux-Le-Grand-Hotel-Le-pressoir-Bordeaux-le-grand-hotel-intercontinental-7-scaled-1.jpg","articleSection":["Noticias"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/bordeaux.intercontinental.com\/es\/le-pressoir-dargent-2-estrellas-en-la-guia-michelin-2018\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/bordeaux.intercontinental.com\/es\/le-pressoir-dargent-2-estrellas-en-la-guia-michelin-2018\/","url":"https:\/\/bordeaux.intercontinental.com\/es\/le-pressoir-dargent-2-estrellas-en-la-guia-michelin-2018\/","name":"Le Pressoir d'Argent : 2 estrellas en la Gu\u00eda Michelin 2018 - InterContinental Bordeaux","isPartOf":{"@id":"https:\/\/bordeaux.intercontinental.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/bordeaux.intercontinental.com\/es\/le-pressoir-dargent-2-estrellas-en-la-guia-michelin-2018\/#primaryimage"},"image":{"@id":"https:\/\/bordeaux.intercontinental.com\/es\/le-pressoir-dargent-2-estrellas-en-la-guia-michelin-2018\/#primaryimage"},"thumbnailUrl":"https:\/\/bordeaux.intercontinental.com\/wp-content\/uploads\/sites\/4\/2022\/07\/InterContinental-Bordeaux-Le-Grand-Hotel-Le-pressoir-Bordeaux-le-grand-hotel-intercontinental-7-scaled-1.jpg","datePublished":"2018-02-05T10:03:00+00:00","dateModified":"2024-02-09T14:51:53+00:00","breadcrumb":{"@id":"https:\/\/bordeaux.intercontinental.com\/es\/le-pressoir-dargent-2-estrellas-en-la-guia-michelin-2018\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/bordeaux.intercontinental.com\/es\/le-pressoir-dargent-2-estrellas-en-la-guia-michelin-2018\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/bordeaux.intercontinental.com\/es\/le-pressoir-dargent-2-estrellas-en-la-guia-michelin-2018\/#primaryimage","url":"https:\/\/bordeaux.intercontinental.com\/wp-content\/uploads\/sites\/4\/2022\/07\/InterContinental-Bordeaux-Le-Grand-Hotel-Le-pressoir-Bordeaux-le-grand-hotel-intercontinental-7-scaled-1.jpg","contentUrl":"https:\/\/bordeaux.intercontinental.com\/wp-content\/uploads\/sites\/4\/2022\/07\/InterContinental-Bordeaux-Le-Grand-Hotel-Le-pressoir-Bordeaux-le-grand-hotel-intercontinental-7-scaled-1.jpg","width":2560,"height":1707},{"@type":"BreadcrumbList","@id":"https:\/\/bordeaux.intercontinental.com\/es\/le-pressoir-dargent-2-estrellas-en-la-guia-michelin-2018\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/bordeaux.intercontinental.com\/es\/"},{"@type":"ListItem","position":2,"name":"Le Pressoir d&rsquo;Argent : 2 estrellas en la Gu\u00eda Michelin 2018"}]},{"@type":"WebSite","@id":"https:\/\/bordeaux.intercontinental.com\/es\/#website","url":"https:\/\/bordeaux.intercontinental.com\/es\/","name":"InterContinental Bordeaux","description":"Live the InterContinental Life","publisher":{"@id":"https:\/\/bordeaux.intercontinental.com\/es\/#organization"},"alternateName":"InterContinental Bordeaux - Le Grand H\u00f4tel","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/bordeaux.intercontinental.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/bordeaux.intercontinental.com\/es\/#organization","name":"InterContinental Bordeaux","alternateName":"InterContinental Bordeaux - Le Grand H\u00f4tel","url":"https:\/\/bordeaux.intercontinental.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/bordeaux.intercontinental.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/bordeaux.intercontinental.com\/wp-content\/uploads\/sites\/4\/2023\/08\/logo-ihg-bordeaux-nl.svg","contentUrl":"https:\/\/bordeaux.intercontinental.com\/wp-content\/uploads\/sites\/4\/2023\/08\/logo-ihg-bordeaux-nl.svg","caption":"InterContinental Bordeaux"},"image":{"@id":"https:\/\/bordeaux.intercontinental.com\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/bordeaux.intercontinental.com\/es\/#\/schema\/person\/16ed2393516772cec016ebdc7d6051e6","name":"netsive","sameAs":["http:\/\/intercontinental.development.netsive.com"]}]}},"_links":{"self":[{"href":"https:\/\/bordeaux.intercontinental.com\/es\/wp-json\/wp\/v2\/posts\/29431","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bordeaux.intercontinental.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bordeaux.intercontinental.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bordeaux.intercontinental.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/bordeaux.intercontinental.com\/es\/wp-json\/wp\/v2\/comments?post=29431"}],"version-history":[{"count":0,"href":"https:\/\/bordeaux.intercontinental.com\/es\/wp-json\/wp\/v2\/posts\/29431\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bordeaux.intercontinental.com\/es\/wp-json\/wp\/v2\/media\/23522"}],"wp:attachment":[{"href":"https:\/\/bordeaux.intercontinental.com\/es\/wp-json\/wp\/v2\/media?parent=29431"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bordeaux.intercontinental.com\/es\/wp-json\/wp\/v2\/categories?post=29431"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bordeaux.intercontinental.com\/es\/wp-json\/wp\/v2\/tags?post=29431"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}