{"id":29421,"date":"2017-03-29T10:59:00","date_gmt":"2017-03-29T08:59:00","guid":{"rendered":"https:\/\/bordeaux.intercontinental.com\/?p=29421"},"modified":"2024-02-09T15:47:24","modified_gmt":"2024-02-09T14:47:24","slug":"chocolat-show","status":"publish","type":"post","link":"https:\/\/bordeaux.intercontinental.com\/es\/chocolat-show\/","title":{"rendered":"\u00abChocolat Show\u00bb"},"content":{"rendered":"\n<p>Del 1 al 30 de abril, venga a descubrir el paquete \u00abchocolat show\u00bb que incluye una noche para dos personas en habitaci\u00f3n doble con desayuno, acceso al Spa y un c\u00f3ctel \u00abchocolate Martini\u00bb por persona. Tendr\u00e1 as\u00ed la oportunidad de admirar \u00abLa mine en chocolat\u00bb, una escultura de nuestro chef pastelero Arthur F\u00e8vre, expuesta del 15 al 23 de abril en el vest\u00edbulo y el bar de L&#8217;Orangerie. Por fin, venga a disfrutar de un Brunch especial de Pascua el domingo 16 de abril de 12:00 a 15:00 en la Brasserie Le Bordeaux Gordon Ramsay.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Del 1 al 30 de abril, venga a descubrir el paquete \u00abchocolat show\u00bb que incluye una noche para dos personas en habitaci\u00f3n doble con desayuno, acceso al Spa y un c\u00f3ctel \u00abchocolate Martini\u00bb por persona. Tendr\u00e1 as\u00ed la oportunidad de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[127],"tags":[],"class_list":["post-29421","post","type-post","status-publish","format-standard","hentry","category-noticias"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>&quot;Chocolat Show&quot; - InterContinental Bordeaux<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/bordeaux.intercontinental.com\/es\/chocolat-show\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"&quot;Chocolat Show&quot; - InterContinental Bordeaux\" \/>\n<meta property=\"og:description\" content=\"Del 1 al 30 de abril, venga a descubrir el paquete \u00abchocolat show\u00bb que incluye una noche para dos personas en habitaci\u00f3n doble con desayuno, acceso al Spa y un c\u00f3ctel \u00abchocolate Martini\u00bb por persona. Tendr\u00e1 as\u00ed la oportunidad de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/bordeaux.intercontinental.com\/es\/chocolat-show\/\" \/>\n<meta property=\"og:site_name\" content=\"InterContinental Bordeaux\" \/>\n<meta property=\"article:published_time\" content=\"2017-03-29T08:59:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-02-09T14:47:24+00:00\" \/>\n<meta name=\"author\" content=\"netsive\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"netsive\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/bordeaux.intercontinental.com\/es\/chocolat-show\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/bordeaux.intercontinental.com\/es\/chocolat-show\/\"},\"author\":{\"name\":\"netsive\",\"@id\":\"https:\/\/bordeaux.intercontinental.com\/es\/#\/schema\/person\/16ed2393516772cec016ebdc7d6051e6\"},\"headline\":\"\u00abChocolat Show\u00bb\",\"datePublished\":\"2017-03-29T08:59:00+00:00\",\"dateModified\":\"2024-02-09T14:47:24+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/bordeaux.intercontinental.com\/es\/chocolat-show\/\"},\"wordCount\":95,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/bordeaux.intercontinental.com\/es\/#organization\"},\"articleSection\":[\"Noticias\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/bordeaux.intercontinental.com\/es\/chocolat-show\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/bordeaux.intercontinental.com\/es\/chocolat-show\/\",\"url\":\"https:\/\/bordeaux.intercontinental.com\/es\/chocolat-show\/\",\"name\":\"\\\"Chocolat Show\\\" - InterContinental Bordeaux\",\"isPartOf\":{\"@id\":\"https:\/\/bordeaux.intercontinental.com\/es\/#website\"},\"datePublished\":\"2017-03-29T08:59:00+00:00\",\"dateModified\":\"2024-02-09T14:47:24+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/bordeaux.intercontinental.com\/es\/chocolat-show\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/bordeaux.intercontinental.com\/es\/chocolat-show\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/bordeaux.intercontinental.com\/es\/chocolat-show\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\/\/bordeaux.intercontinental.com\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00ab\u00a0Chocolat Show\u00a0\u00bb\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/bordeaux.intercontinental.com\/es\/#website\",\"url\":\"https:\/\/bordeaux.intercontinental.com\/es\/\",\"name\":\"InterContinental Bordeaux\",\"description\":\"Live the InterContinental Life\",\"publisher\":{\"@id\":\"https:\/\/bordeaux.intercontinental.com\/es\/#organization\"},\"alternateName\":\"InterContinental Bordeaux - Le Grand H\u00f4tel\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/bordeaux.intercontinental.com\/es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/bordeaux.intercontinental.com\/es\/#organization\",\"name\":\"InterContinental Bordeaux\",\"alternateName\":\"InterContinental Bordeaux - Le Grand H\u00f4tel\",\"url\":\"https:\/\/bordeaux.intercontinental.com\/es\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/bordeaux.intercontinental.com\/es\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/bordeaux.intercontinental.com\/wp-content\/uploads\/sites\/4\/2023\/08\/logo-ihg-bordeaux-nl.svg\",\"contentUrl\":\"https:\/\/bordeaux.intercontinental.com\/wp-content\/uploads\/sites\/4\/2023\/08\/logo-ihg-bordeaux-nl.svg\",\"caption\":\"InterContinental Bordeaux\"},\"image\":{\"@id\":\"https:\/\/bordeaux.intercontinental.com\/es\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/bordeaux.intercontinental.com\/es\/#\/schema\/person\/16ed2393516772cec016ebdc7d6051e6\",\"name\":\"netsive\",\"sameAs\":[\"http:\/\/intercontinental.development.netsive.com\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\"Chocolat Show\" - InterContinental Bordeaux","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/bordeaux.intercontinental.com\/es\/chocolat-show\/","og_locale":"es_ES","og_type":"article","og_title":"\"Chocolat Show\" - InterContinental Bordeaux","og_description":"Del 1 al 30 de abril, venga a descubrir el paquete \u00abchocolat show\u00bb que incluye una noche para dos personas en habitaci\u00f3n doble con desayuno, acceso al Spa y un c\u00f3ctel \u00abchocolate Martini\u00bb por persona. Tendr\u00e1 as\u00ed la oportunidad de [&hellip;]","og_url":"https:\/\/bordeaux.intercontinental.com\/es\/chocolat-show\/","og_site_name":"InterContinental Bordeaux","article_published_time":"2017-03-29T08:59:00+00:00","article_modified_time":"2024-02-09T14:47:24+00:00","author":"netsive","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"netsive","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/bordeaux.intercontinental.com\/es\/chocolat-show\/#article","isPartOf":{"@id":"https:\/\/bordeaux.intercontinental.com\/es\/chocolat-show\/"},"author":{"name":"netsive","@id":"https:\/\/bordeaux.intercontinental.com\/es\/#\/schema\/person\/16ed2393516772cec016ebdc7d6051e6"},"headline":"\u00abChocolat Show\u00bb","datePublished":"2017-03-29T08:59:00+00:00","dateModified":"2024-02-09T14:47:24+00:00","mainEntityOfPage":{"@id":"https:\/\/bordeaux.intercontinental.com\/es\/chocolat-show\/"},"wordCount":95,"commentCount":0,"publisher":{"@id":"https:\/\/bordeaux.intercontinental.com\/es\/#organization"},"articleSection":["Noticias"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/bordeaux.intercontinental.com\/es\/chocolat-show\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/bordeaux.intercontinental.com\/es\/chocolat-show\/","url":"https:\/\/bordeaux.intercontinental.com\/es\/chocolat-show\/","name":"\"Chocolat Show\" - InterContinental Bordeaux","isPartOf":{"@id":"https:\/\/bordeaux.intercontinental.com\/es\/#website"},"datePublished":"2017-03-29T08:59:00+00:00","dateModified":"2024-02-09T14:47:24+00:00","breadcrumb":{"@id":"https:\/\/bordeaux.intercontinental.com\/es\/chocolat-show\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/bordeaux.intercontinental.com\/es\/chocolat-show\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/bordeaux.intercontinental.com\/es\/chocolat-show\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/bordeaux.intercontinental.com\/es\/"},{"@type":"ListItem","position":2,"name":"\u00ab\u00a0Chocolat Show\u00a0\u00bb"}]},{"@type":"WebSite","@id":"https:\/\/bordeaux.intercontinental.com\/es\/#website","url":"https:\/\/bordeaux.intercontinental.com\/es\/","name":"InterContinental Bordeaux","description":"Live the InterContinental Life","publisher":{"@id":"https:\/\/bordeaux.intercontinental.com\/es\/#organization"},"alternateName":"InterContinental Bordeaux - Le Grand H\u00f4tel","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/bordeaux.intercontinental.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/bordeaux.intercontinental.com\/es\/#organization","name":"InterContinental Bordeaux","alternateName":"InterContinental Bordeaux - Le Grand H\u00f4tel","url":"https:\/\/bordeaux.intercontinental.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/bordeaux.intercontinental.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/bordeaux.intercontinental.com\/wp-content\/uploads\/sites\/4\/2023\/08\/logo-ihg-bordeaux-nl.svg","contentUrl":"https:\/\/bordeaux.intercontinental.com\/wp-content\/uploads\/sites\/4\/2023\/08\/logo-ihg-bordeaux-nl.svg","caption":"InterContinental Bordeaux"},"image":{"@id":"https:\/\/bordeaux.intercontinental.com\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/bordeaux.intercontinental.com\/es\/#\/schema\/person\/16ed2393516772cec016ebdc7d6051e6","name":"netsive","sameAs":["http:\/\/intercontinental.development.netsive.com"]}]}},"_links":{"self":[{"href":"https:\/\/bordeaux.intercontinental.com\/es\/wp-json\/wp\/v2\/posts\/29421","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bordeaux.intercontinental.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bordeaux.intercontinental.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bordeaux.intercontinental.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/bordeaux.intercontinental.com\/es\/wp-json\/wp\/v2\/comments?post=29421"}],"version-history":[{"count":0,"href":"https:\/\/bordeaux.intercontinental.com\/es\/wp-json\/wp\/v2\/posts\/29421\/revisions"}],"wp:attachment":[{"href":"https:\/\/bordeaux.intercontinental.com\/es\/wp-json\/wp\/v2\/media?parent=29421"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bordeaux.intercontinental.com\/es\/wp-json\/wp\/v2\/categories?post=29421"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bordeaux.intercontinental.com\/es\/wp-json\/wp\/v2\/tags?post=29421"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}