{"id":5001,"date":"2018-12-03T11:24:00","date_gmt":"2018-12-03T10:24:00","guid":{"rendered":"https:\/\/bordeaux.intercontinental.com\/?p=5001"},"modified":"2022-10-26T15:33:09","modified_gmt":"2022-10-26T13:33:09","slug":"advent-calendar-december-1-2018","status":"publish","type":"post","link":"https:\/\/bordeaux.intercontinental.com\/en\/advent-calendar-december-1-2018\/","title":{"rendered":"Advent Calendar &#8211; December 1, 2018"},"content":{"rendered":"\n<p>At the Intercontinental Bordeaux \u2013 Le Grand H\u00f4tel, the whole family is pampered. A night in a Junior Suite with breakfast has already been won on Sunday on our Instagram account via our advent calendar. Join us and follow us on Instagram @intercontinental_bordeaux<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Box 1 &#8211; It&#8217;s up to you!<\/p>\n","protected":false},"author":1,"featured_media":223,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[50],"tags":[],"class_list":["post-5001","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Advent Calendar - December 1, 2018 - InterContinental Bordeaux<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/bordeaux.intercontinental.com\/en\/advent-calendar-december-1-2018\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Advent Calendar - December 1, 2018 - InterContinental Bordeaux\" \/>\n<meta property=\"og:description\" content=\"Box 1 - It&#039;s up to you!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/bordeaux.intercontinental.com\/en\/advent-calendar-december-1-2018\/\" \/>\n<meta property=\"og:site_name\" content=\"InterContinental Bordeaux\" \/>\n<meta property=\"article:published_time\" content=\"2018-12-03T10:24:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-10-26T13:33:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/bordeaux.intercontinental.com\/wp-content\/uploads\/sites\/4\/2022\/07\/InterContinental-Bordeaux-Le-Grand-Hotel-GDHOTEL_CalendrierAvent-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"601\" \/>\n\t<meta property=\"og:image:height\" content=\"471\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"netsive\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"netsive\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/bordeaux.intercontinental.com\/en\/advent-calendar-december-1-2018\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/bordeaux.intercontinental.com\/en\/advent-calendar-december-1-2018\/\"},\"author\":{\"name\":\"netsive\",\"@id\":\"https:\/\/bordeaux.intercontinental.com\/en\/#\/schema\/person\/16ed2393516772cec016ebdc7d6051e6\"},\"headline\":\"Advent Calendar &#8211; December 1, 2018\",\"datePublished\":\"2018-12-03T10:24:00+00:00\",\"dateModified\":\"2022-10-26T13:33:09+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/bordeaux.intercontinental.com\/en\/advent-calendar-december-1-2018\/\"},\"wordCount\":48,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/bordeaux.intercontinental.com\/en\/#organization\"},\"image\":{\"@id\":\"https:\/\/bordeaux.intercontinental.com\/en\/advent-calendar-december-1-2018\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/bordeaux.intercontinental.com\/wp-content\/uploads\/sites\/4\/2022\/07\/InterContinental-Bordeaux-Le-Grand-Hotel-GDHOTEL_CalendrierAvent-2.jpg\",\"articleSection\":[\"News\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/bordeaux.intercontinental.com\/en\/advent-calendar-december-1-2018\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/bordeaux.intercontinental.com\/en\/advent-calendar-december-1-2018\/\",\"url\":\"https:\/\/bordeaux.intercontinental.com\/en\/advent-calendar-december-1-2018\/\",\"name\":\"Advent Calendar - December 1, 2018 - InterContinental Bordeaux\",\"isPartOf\":{\"@id\":\"https:\/\/bordeaux.intercontinental.com\/en\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/bordeaux.intercontinental.com\/en\/advent-calendar-december-1-2018\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/bordeaux.intercontinental.com\/en\/advent-calendar-december-1-2018\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/bordeaux.intercontinental.com\/wp-content\/uploads\/sites\/4\/2022\/07\/InterContinental-Bordeaux-Le-Grand-Hotel-GDHOTEL_CalendrierAvent-2.jpg\",\"datePublished\":\"2018-12-03T10:24:00+00:00\",\"dateModified\":\"2022-10-26T13:33:09+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/bordeaux.intercontinental.com\/en\/advent-calendar-december-1-2018\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/bordeaux.intercontinental.com\/en\/advent-calendar-december-1-2018\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/bordeaux.intercontinental.com\/en\/advent-calendar-december-1-2018\/#primaryimage\",\"url\":\"https:\/\/bordeaux.intercontinental.com\/wp-content\/uploads\/sites\/4\/2022\/07\/InterContinental-Bordeaux-Le-Grand-Hotel-GDHOTEL_CalendrierAvent-2.jpg\",\"contentUrl\":\"https:\/\/bordeaux.intercontinental.com\/wp-content\/uploads\/sites\/4\/2022\/07\/InterContinental-Bordeaux-Le-Grand-Hotel-GDHOTEL_CalendrierAvent-2.jpg\",\"width\":601,\"height\":471},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/bordeaux.intercontinental.com\/en\/advent-calendar-december-1-2018\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/bordeaux.intercontinental.com\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Advent Calendar &#8211; December 1, 2018\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/bordeaux.intercontinental.com\/en\/#website\",\"url\":\"https:\/\/bordeaux.intercontinental.com\/en\/\",\"name\":\"InterContinental Bordeaux\",\"description\":\"Live the InterContinental Life\",\"publisher\":{\"@id\":\"https:\/\/bordeaux.intercontinental.com\/en\/#organization\"},\"alternateName\":\"InterContinental Bordeaux - Le Grand H\u00f4tel\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/bordeaux.intercontinental.com\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/bordeaux.intercontinental.com\/en\/#organization\",\"name\":\"InterContinental Bordeaux\",\"alternateName\":\"InterContinental Bordeaux - Le Grand H\u00f4tel\",\"url\":\"https:\/\/bordeaux.intercontinental.com\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/bordeaux.intercontinental.com\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/bordeaux.intercontinental.com\/wp-content\/uploads\/sites\/4\/2023\/08\/logo-ihg-bordeaux-nl.svg\",\"contentUrl\":\"https:\/\/bordeaux.intercontinental.com\/wp-content\/uploads\/sites\/4\/2023\/08\/logo-ihg-bordeaux-nl.svg\",\"caption\":\"InterContinental Bordeaux\"},\"image\":{\"@id\":\"https:\/\/bordeaux.intercontinental.com\/en\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/bordeaux.intercontinental.com\/en\/#\/schema\/person\/16ed2393516772cec016ebdc7d6051e6\",\"name\":\"netsive\",\"sameAs\":[\"http:\/\/intercontinental.development.netsive.com\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Advent Calendar - December 1, 2018 - InterContinental Bordeaux","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/bordeaux.intercontinental.com\/en\/advent-calendar-december-1-2018\/","og_locale":"en_US","og_type":"article","og_title":"Advent Calendar - December 1, 2018 - InterContinental Bordeaux","og_description":"Box 1 - It's up to you!","og_url":"https:\/\/bordeaux.intercontinental.com\/en\/advent-calendar-december-1-2018\/","og_site_name":"InterContinental Bordeaux","article_published_time":"2018-12-03T10:24:00+00:00","article_modified_time":"2022-10-26T13:33:09+00:00","og_image":[{"width":601,"height":471,"url":"https:\/\/bordeaux.intercontinental.com\/wp-content\/uploads\/sites\/4\/2022\/07\/InterContinental-Bordeaux-Le-Grand-Hotel-GDHOTEL_CalendrierAvent-2.jpg","type":"image\/jpeg"}],"author":"netsive","twitter_card":"summary_large_image","twitter_misc":{"Written by":"netsive","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/bordeaux.intercontinental.com\/en\/advent-calendar-december-1-2018\/#article","isPartOf":{"@id":"https:\/\/bordeaux.intercontinental.com\/en\/advent-calendar-december-1-2018\/"},"author":{"name":"netsive","@id":"https:\/\/bordeaux.intercontinental.com\/en\/#\/schema\/person\/16ed2393516772cec016ebdc7d6051e6"},"headline":"Advent Calendar &#8211; December 1, 2018","datePublished":"2018-12-03T10:24:00+00:00","dateModified":"2022-10-26T13:33:09+00:00","mainEntityOfPage":{"@id":"https:\/\/bordeaux.intercontinental.com\/en\/advent-calendar-december-1-2018\/"},"wordCount":48,"commentCount":0,"publisher":{"@id":"https:\/\/bordeaux.intercontinental.com\/en\/#organization"},"image":{"@id":"https:\/\/bordeaux.intercontinental.com\/en\/advent-calendar-december-1-2018\/#primaryimage"},"thumbnailUrl":"https:\/\/bordeaux.intercontinental.com\/wp-content\/uploads\/sites\/4\/2022\/07\/InterContinental-Bordeaux-Le-Grand-Hotel-GDHOTEL_CalendrierAvent-2.jpg","articleSection":["News"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/bordeaux.intercontinental.com\/en\/advent-calendar-december-1-2018\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/bordeaux.intercontinental.com\/en\/advent-calendar-december-1-2018\/","url":"https:\/\/bordeaux.intercontinental.com\/en\/advent-calendar-december-1-2018\/","name":"Advent Calendar - December 1, 2018 - InterContinental Bordeaux","isPartOf":{"@id":"https:\/\/bordeaux.intercontinental.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/bordeaux.intercontinental.com\/en\/advent-calendar-december-1-2018\/#primaryimage"},"image":{"@id":"https:\/\/bordeaux.intercontinental.com\/en\/advent-calendar-december-1-2018\/#primaryimage"},"thumbnailUrl":"https:\/\/bordeaux.intercontinental.com\/wp-content\/uploads\/sites\/4\/2022\/07\/InterContinental-Bordeaux-Le-Grand-Hotel-GDHOTEL_CalendrierAvent-2.jpg","datePublished":"2018-12-03T10:24:00+00:00","dateModified":"2022-10-26T13:33:09+00:00","breadcrumb":{"@id":"https:\/\/bordeaux.intercontinental.com\/en\/advent-calendar-december-1-2018\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/bordeaux.intercontinental.com\/en\/advent-calendar-december-1-2018\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/bordeaux.intercontinental.com\/en\/advent-calendar-december-1-2018\/#primaryimage","url":"https:\/\/bordeaux.intercontinental.com\/wp-content\/uploads\/sites\/4\/2022\/07\/InterContinental-Bordeaux-Le-Grand-Hotel-GDHOTEL_CalendrierAvent-2.jpg","contentUrl":"https:\/\/bordeaux.intercontinental.com\/wp-content\/uploads\/sites\/4\/2022\/07\/InterContinental-Bordeaux-Le-Grand-Hotel-GDHOTEL_CalendrierAvent-2.jpg","width":601,"height":471},{"@type":"BreadcrumbList","@id":"https:\/\/bordeaux.intercontinental.com\/en\/advent-calendar-december-1-2018\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/bordeaux.intercontinental.com\/en\/"},{"@type":"ListItem","position":2,"name":"Advent Calendar &#8211; December 1, 2018"}]},{"@type":"WebSite","@id":"https:\/\/bordeaux.intercontinental.com\/en\/#website","url":"https:\/\/bordeaux.intercontinental.com\/en\/","name":"InterContinental Bordeaux","description":"Live the InterContinental Life","publisher":{"@id":"https:\/\/bordeaux.intercontinental.com\/en\/#organization"},"alternateName":"InterContinental Bordeaux - Le Grand H\u00f4tel","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/bordeaux.intercontinental.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/bordeaux.intercontinental.com\/en\/#organization","name":"InterContinental Bordeaux","alternateName":"InterContinental Bordeaux - Le Grand H\u00f4tel","url":"https:\/\/bordeaux.intercontinental.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/bordeaux.intercontinental.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/bordeaux.intercontinental.com\/wp-content\/uploads\/sites\/4\/2023\/08\/logo-ihg-bordeaux-nl.svg","contentUrl":"https:\/\/bordeaux.intercontinental.com\/wp-content\/uploads\/sites\/4\/2023\/08\/logo-ihg-bordeaux-nl.svg","caption":"InterContinental Bordeaux"},"image":{"@id":"https:\/\/bordeaux.intercontinental.com\/en\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/bordeaux.intercontinental.com\/en\/#\/schema\/person\/16ed2393516772cec016ebdc7d6051e6","name":"netsive","sameAs":["http:\/\/intercontinental.development.netsive.com"]}]}},"_links":{"self":[{"href":"https:\/\/bordeaux.intercontinental.com\/en\/wp-json\/wp\/v2\/posts\/5001","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bordeaux.intercontinental.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bordeaux.intercontinental.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bordeaux.intercontinental.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/bordeaux.intercontinental.com\/en\/wp-json\/wp\/v2\/comments?post=5001"}],"version-history":[{"count":0,"href":"https:\/\/bordeaux.intercontinental.com\/en\/wp-json\/wp\/v2\/posts\/5001\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bordeaux.intercontinental.com\/en\/wp-json\/wp\/v2\/media\/223"}],"wp:attachment":[{"href":"https:\/\/bordeaux.intercontinental.com\/en\/wp-json\/wp\/v2\/media?parent=5001"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bordeaux.intercontinental.com\/en\/wp-json\/wp\/v2\/categories?post=5001"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bordeaux.intercontinental.com\/en\/wp-json\/wp\/v2\/tags?post=5001"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}